{"id":1203,"date":"2020-07-16T17:54:33","date_gmt":"2020-07-16T17:54:33","guid":{"rendered":"https:\/\/joom.cipdd.org\/?p=1203"},"modified":"2025-11-03T17:57:24","modified_gmt":"2025-11-03T17:57:24","slug":"%e1%83%9b%e1%83%a1%e1%83%9d%e1%83%a4%e1%83%9a%e1%83%98%e1%83%9d-%e1%83%a0%e1%83%94%e1%83%9a%e1%83%98%e1%83%92%e1%83%98%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%99%e1%83%9a%e1%83%a3%e1%83%91-2","status":"publish","type":"post","link":"https:\/\/joom.cipdd.org\/en\/%e1%83%9b%e1%83%a1%e1%83%9d%e1%83%a4%e1%83%9a%e1%83%98%e1%83%9d-%e1%83%a0%e1%83%94%e1%83%9a%e1%83%98%e1%83%92%e1%83%98%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%99%e1%83%9a%e1%83%a3%e1%83%91-2\/","title":{"rendered":"Club of World Religions renewed in Akhaltsikhe!"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1203\" class=\"elementor elementor-1203\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65377da9 e-flex e-con-boxed e-con e-parent\" data-id=\"65377da9\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a76dcd2 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"a76dcd2\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 7\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/joom.cipdd.org\/wp-content\/uploads\/2025\/11\/Gallery_41596800980-150x150.jpg\" alt=\"Gallery_41596800980\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 7\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/joom.cipdd.org\/wp-content\/uploads\/2025\/11\/Gallery_21596800980-150x150.jpg\" alt=\"Gallery_21596800980\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 7\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/joom.cipdd.org\/wp-content\/uploads\/2025\/11\/Gallery_51596800980-150x150.jpg\" alt=\"Gallery_51596800980\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 7\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/joom.cipdd.org\/wp-content\/uploads\/2025\/11\/Galley_221596800980-150x150.jpg\" alt=\"Galley_221596800980\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 7\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/joom.cipdd.org\/wp-content\/uploads\/2025\/11\/Galley_221596800980-1-150x150.jpg\" alt=\"Galley_221596800980 (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 7\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/joom.cipdd.org\/wp-content\/uploads\/2025\/11\/News_1596800822-150x150.jpg\" alt=\"News_1596800822\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 7\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/joom.cipdd.org\/wp-content\/uploads\/2025\/11\/Gallery_61596800980-150x150.jpg\" alt=\"Gallery_61596800980\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74c6682c elementor-widget elementor-widget-text-editor\" data-id=\"74c6682c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t\n<p class=\"wp-block-paragraph\">Club of World Religions Renewed in Akhaltsikhe! Participants from Akhaltsikhe and Akhalkalaki heard a lecture on Judaism. Speakers: Merab Ghaganidze, Professor of the Free University and Keti Kakitelashvili, Professor of Tbilisi State University.<br>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u10db\u10dd\u10dc\u10d0\u10ec\u10d8\u10da\u10d4\u10d4\u10d1\u10db\u10d0 \u10d0\u10ee\u10d0\u10da\u10ea\u10d8\u10ee\u10d8\u10d3\u10d0\u10dc \u10d3\u10d0 \u10d0\u10ee\u10d0\u10da\u10e5\u10d0\u10da\u10d0\u10e5\u10d8\u10d3\u10d0\u10dc \u10db\u10dd\u10d8\u10e1\u10db\u10d8\u10dc\u10d4\u10e1 \u10da\u10d4\u10e5\u10ea\u10d8\u10d0 \u10d8\u10e3\u10d3\u10d0\u10d8\u10d6\u10db\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1. \u10db\u10dd\u10db\u10ee\u10e1\u10d4\u10dc\u10d4\u10d1\u10da\u10d4\u10d1\u10d8:\u10db\u10d4\u10e0\u10d0\u10d1 \u10e6\u10d0\u10e6\u10d0\u10dc\u10d8\u10eb\u10d4, \u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10d0\u10da\u10d8 \u10e3\u10dc\u10d8\u10d5\u10d4\u10e0\u10e1\u10d8\u10e2\u10d4\u10e2\u10d8\u10e1 \u10de\u10e0\u10dd\u10e4\u10d4\u10e1\u10dd\u10e0\u10d8 \u10d3\u10d0 \u10e5\u10d4\u10d7\u10d8 \u10d9\u10d0\u10d9\u10d8\u10e2\u10d4\u10da\u10d0\u10e8\u10d5\u10d8\u10da\u10d8, \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10e1\u10d0\u10ee\u10d4\u10da\u10db\u10ec\u10d8\u10e4\u10dd \u10e3\u10dc\u10d8\u10d5\u10d4\u10e0\u10e1\u10d8\u10e2\u10d4\u10e2\u10d8\u10e1 \u10de\u10e0\u10dd\u10e4\u10d4\u10e1\u10dd\u10e0\u10d8.\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10e1 \u10d0\u10dc\u10ee\u10dd\u10e0\u10ea\u10d8\u10d4\u10da\u10d4\u10d1\u10e1 \u10db\u10e8\u10d5\u10d8\u10d3\u10dd\u10d1\u10d8\u10e1, \u10d3\u10d4\u10db\u10dd\u10d9\u10e0\u10d0\u10e2\u10d8\u10d8\u10e1 \u10d3\u10d0 \u10d2\u10d0\u10dc\u10d5\u10d8\u10d7\u10d0\u10e0\u10d4\u10d1\u10d8\u10e1 \u10d9\u10d0\u10d5\u10d9\u10d0\u10e1\u10d8\u10e3\u10e0\u10d8 \u10d8\u10dc\u10e1\u10e2\u10d8\u10e2\u10e3\u10e2\u10d8 (CIPDD) \u10d3\u10d0 \u10d9\u10dd\u10dc\u10e0\u10d0\u10d3 \u10d0\u10d3\u10d4\u10dc\u10d0\u10e3\u10d4\u10e0\u10d8\u10e1 \u10e4\u10dd\u10dc\u10d3\u10d8\u10e1 \u10e1\u10d0\u10db\u10ee\u10e0\u10d4\u10d7 \u10d9\u10d0\u10d5\u10d9\u10d0\u10e1\u10d8\u10d8\u10e1 \u10e0\u10d4\u10d2\u10d8\u10dd\u10dc\u10d0\u10da\u10e3\u10e0\u10d8 \u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d0 (KAS) \u10d0\u10ee\u10d0\u10da\u10ea\u10d8\u10ee\u10d8\u10e1 \u10d0\u10d3\u10d2\u10d8\u10da\u10dd\u10d1\u10e0\u10d8\u10d5 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d0\u10e1\u10d7\u10d0\u10dc, \u10d3\u10d4\u10db\u10dd\u10d9\u10e0\u10d0\u10e2 \u10db\u10d4\u10e1\u10ee\u10d7\u10d0 \u10d9\u10d0\u10d5\u10e8\u10d8\u10e0\u10d7\u10d0\u10dc (UDM) \u10d4\u10e0\u10d7\u10d0\u10d3. Konrad Adenauer Stiftung South Caucasus \u10d3\u10d4\u10db\u10dd\u10d9\u10e0\u10d0\u10e2 \u10db\u10d4\u10e1\u10ee\u10d7\u10d0 \u10d9\u10d0\u10d5\u10e8\u10d8\u10e0\u10d8\/Union of Democrat [&hellip;]<\/p>","protected":false},"author":1,"featured_media":1204,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/joom.cipdd.org\/en\/wp-json\/wp\/v2\/posts\/1203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joom.cipdd.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/joom.cipdd.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/joom.cipdd.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/joom.cipdd.org\/en\/wp-json\/wp\/v2\/comments?post=1203"}],"version-history":[{"count":4,"href":"https:\/\/joom.cipdd.org\/en\/wp-json\/wp\/v2\/posts\/1203\/revisions"}],"predecessor-version":[{"id":1214,"href":"https:\/\/joom.cipdd.org\/en\/wp-json\/wp\/v2\/posts\/1203\/revisions\/1214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/joom.cipdd.org\/en\/wp-json\/wp\/v2\/media\/1204"}],"wp:attachment":[{"href":"https:\/\/joom.cipdd.org\/en\/wp-json\/wp\/v2\/media?parent=1203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/joom.cipdd.org\/en\/wp-json\/wp\/v2\/categories?post=1203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/joom.cipdd.org\/en\/wp-json\/wp\/v2\/tags?post=1203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}